{"id":7502,"date":"2021-07-15T16:45:43","date_gmt":"2021-07-15T14:45:43","guid":{"rendered":"https:\/\/www.flipo-richir.eu\/wp-content\/uploads\/mise-en-service-du-6-eme-groupe-de-la-centrale-hydroelectrique-dedea-l-flipo-richir-3.jpg"},"modified":"2021-07-15T16:45:43","modified_gmt":"2021-07-15T14:45:43","slug":"mise-en-service-du-6-eme-groupe-de-la-centrale-hydroelectrique-dedea-l-flipo-richir-3-2","status":"inherit","type":"attachment","link":"https:\/\/www.flipo-richir.eu\/en\/mise-en-service-du-6-eme-groupe-de-la-centrale-hydroelectrique-dedea-l-flipo-richir-3-2\/","title":{"rendered":"Mise en service du 6 e\u0300me groupe de la centrale hydroe\u0301lectrique d&#8217;EDEA l Flipo Richir 3"},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-7502","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mise en service du 6 e\u0300me groupe de la centrale hydroe\u0301lectrique d&#039;EDEA l Flipo Richir 3 - Flipo Richir<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.flipo-richir.eu\/wp-content\/uploads\/mise-en-service-du-6-eme-groupe-de-la-centrale-hydroelectrique-dedea-l-flipo-richir-3.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mise en service du 6 e\u0300me groupe de la centrale hydroe\u0301lectrique d&#039;EDEA l Flipo Richir 3 - Flipo Richir\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.flipo-richir.eu\/wp-content\/uploads\/mise-en-service-du-6-eme-groupe-de-la-centrale-hydroelectrique-dedea-l-flipo-richir-3.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Flipo Richir\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.flipo-richir.eu\/wp-content\/uploads\/mise-en-service-du-6-eme-groupe-de-la-centrale-hydroelectrique-dedea-l-flipo-richir-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.flipo-richir.eu\\\/wp-content\\\/uploads\\\/mise-en-service-du-6-eme-groupe-de-la-centrale-hydroelectrique-dedea-l-flipo-richir-3.jpg\",\"url\":\"https:\\\/\\\/www.flipo-richir.eu\\\/wp-content\\\/uploads\\\/mise-en-service-du-6-eme-groupe-de-la-centrale-hydroelectrique-dedea-l-flipo-richir-3.jpg\",\"name\":\"Mise en service du 6 e\u0300me groupe de la centrale hydroe\u0301lectrique d'EDEA l Flipo Richir 3 - Flipo Richir\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.flipo-richir.eu\\\/#website\"},\"datePublished\":\"2021-07-15T14:45:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.flipo-richir.eu\\\/wp-content\\\/uploads\\\/mise-en-service-du-6-eme-groupe-de-la-centrale-hydroelectrique-dedea-l-flipo-richir-3.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.flipo-richir.eu\\\/wp-content\\\/uploads\\\/mise-en-service-du-6-eme-groupe-de-la-centrale-hydroelectrique-dedea-l-flipo-richir-3.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.flipo-richir.eu\\\/wp-content\\\/uploads\\\/mise-en-service-du-6-eme-groupe-de-la-centrale-hydroelectrique-dedea-l-flipo-richir-3.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.flipo-richir.eu\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mise en service du 6 e\u0300me groupe de la centrale hydroe\u0301lectrique d&#8217;EDEA l Flipo Richir 3\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.flipo-richir.eu\\\/#website\",\"url\":\"https:\\\/\\\/www.flipo-richir.eu\\\/\",\"name\":\"Flipo Richir\",\"description\":\"L&#039;Energie en Services, maintenance industrielle, maintenance \u00e9lectrique\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.flipo-richir.eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.flipo-richir.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.flipo-richir.eu\\\/#organization\",\"name\":\"FLIPO RICHIR\",\"url\":\"https:\\\/\\\/www.flipo-richir.eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.flipo-richir.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"FLIPO RICHIR\"},\"image\":{\"@id\":\"https:\\\/\\\/www.flipo-richir.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mise en service du 6 e\u0300me groupe de la centrale hydroe\u0301lectrique d'EDEA l Flipo Richir 3 - Flipo Richir","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.flipo-richir.eu\/wp-content\/uploads\/mise-en-service-du-6-eme-groupe-de-la-centrale-hydroelectrique-dedea-l-flipo-richir-3.jpg","og_locale":"en_US","og_type":"article","og_title":"Mise en service du 6 e\u0300me groupe de la centrale hydroe\u0301lectrique d'EDEA l Flipo Richir 3 - Flipo Richir","og_url":"https:\/\/www.flipo-richir.eu\/wp-content\/uploads\/mise-en-service-du-6-eme-groupe-de-la-centrale-hydroelectrique-dedea-l-flipo-richir-3.jpg","og_site_name":"Flipo Richir","og_image":[{"width":1200,"height":1600,"url":"https:\/\/www.flipo-richir.eu\/wp-content\/uploads\/mise-en-service-du-6-eme-groupe-de-la-centrale-hydroelectrique-dedea-l-flipo-richir-3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.flipo-richir.eu\/wp-content\/uploads\/mise-en-service-du-6-eme-groupe-de-la-centrale-hydroelectrique-dedea-l-flipo-richir-3.jpg","url":"https:\/\/www.flipo-richir.eu\/wp-content\/uploads\/mise-en-service-du-6-eme-groupe-de-la-centrale-hydroelectrique-dedea-l-flipo-richir-3.jpg","name":"Mise en service du 6 e\u0300me groupe de la centrale hydroe\u0301lectrique d'EDEA l Flipo Richir 3 - Flipo Richir","isPartOf":{"@id":"https:\/\/www.flipo-richir.eu\/#website"},"datePublished":"2021-07-15T14:45:43+00:00","breadcrumb":{"@id":"https:\/\/www.flipo-richir.eu\/wp-content\/uploads\/mise-en-service-du-6-eme-groupe-de-la-centrale-hydroelectrique-dedea-l-flipo-richir-3.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.flipo-richir.eu\/wp-content\/uploads\/mise-en-service-du-6-eme-groupe-de-la-centrale-hydroelectrique-dedea-l-flipo-richir-3.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.flipo-richir.eu\/wp-content\/uploads\/mise-en-service-du-6-eme-groupe-de-la-centrale-hydroelectrique-dedea-l-flipo-richir-3.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.flipo-richir.eu\/en\/"},{"@type":"ListItem","position":2,"name":"Mise en service du 6 e\u0300me groupe de la centrale hydroe\u0301lectrique d&#8217;EDEA l Flipo Richir 3"}]},{"@type":"WebSite","@id":"https:\/\/www.flipo-richir.eu\/#website","url":"https:\/\/www.flipo-richir.eu\/","name":"Flipo Richir","description":"L&#039;Energie en Services, maintenance industrielle, maintenance \u00e9lectrique","publisher":{"@id":"https:\/\/www.flipo-richir.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.flipo-richir.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.flipo-richir.eu\/#organization","name":"FLIPO RICHIR","url":"https:\/\/www.flipo-richir.eu\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.flipo-richir.eu\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"FLIPO RICHIR"},"image":{"@id":"https:\/\/www.flipo-richir.eu\/#\/schema\/logo\/image\/"}}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.flipo-richir.eu\/wp-content\/uploads\/mise-en-service-du-6-eme-groupe-de-la-centrale-hydroelectrique-dedea-l-flipo-richir-3.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/www.flipo-richir.eu\/wp-content\/uploads\/mise-en-service-du-6-eme-groupe-de-la-centrale-hydroelectrique-dedea-l-flipo-richir-3-225x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.flipo-richir.eu\/wp-content\/uploads\/mise-en-service-du-6-eme-groupe-de-la-centrale-hydroelectrique-dedea-l-flipo-richir-3-225x300.jpg 225w, https:\/\/www.flipo-richir.eu\/wp-content\/uploads\/mise-en-service-du-6-eme-groupe-de-la-centrale-hydroelectrique-dedea-l-flipo-richir-3-768x1024.jpg 768w, https:\/\/www.flipo-richir.eu\/wp-content\/uploads\/mise-en-service-du-6-eme-groupe-de-la-centrale-hydroelectrique-dedea-l-flipo-richir-3-1152x1536.jpg 1152w, https:\/\/www.flipo-richir.eu\/wp-content\/uploads\/mise-en-service-du-6-eme-groupe-de-la-centrale-hydroelectrique-dedea-l-flipo-richir-3.jpg 1200w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1200,"height":1600,"file":"mise-en-service-du-6-eme-groupe-de-la-centrale-hydroelectrique-dedea-l-flipo-richir-3.jpg","sizes":{"medium":{"file":"mise-en-service-du-6-eme-groupe-de-la-centrale-hydroelectrique-dedea-l-flipo-richir-3-225x300.jpg","width":225,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/www.flipo-richir.eu\/wp-content\/uploads\/mise-en-service-du-6-eme-groupe-de-la-centrale-hydroelectrique-dedea-l-flipo-richir-3-225x300.jpg"},"large":{"file":"mise-en-service-du-6-eme-groupe-de-la-centrale-hydroelectrique-dedea-l-flipo-richir-3-768x1024.jpg","width":768,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/www.flipo-richir.eu\/wp-content\/uploads\/mise-en-service-du-6-eme-groupe-de-la-centrale-hydroelectrique-dedea-l-flipo-richir-3-768x1024.jpg"},"thumbnail":{"file":"mise-en-service-du-6-eme-groupe-de-la-centrale-hydroelectrique-dedea-l-flipo-richir-3-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.flipo-richir.eu\/wp-content\/uploads\/mise-en-service-du-6-eme-groupe-de-la-centrale-hydroelectrique-dedea-l-flipo-richir-3-150x150.jpg"},"1536x1536":{"file":"mise-en-service-du-6-eme-groupe-de-la-centrale-hydroelectrique-dedea-l-flipo-richir-3-1152x1536.jpg","width":1152,"height":1536,"mime_type":"image\/jpeg","source_url":"https:\/\/www.flipo-richir.eu\/wp-content\/uploads\/mise-en-service-du-6-eme-groupe-de-la-centrale-hydroelectrique-dedea-l-flipo-richir-3-1152x1536.jpg"},"grve-image-extrasmall-square":{"file":"mise-en-service-du-6-eme-groupe-de-la-centrale-hydroelectrique-dedea-l-flipo-richir-3-80x80.jpg","width":80,"height":80,"mime_type":"image\/jpeg","source_url":"https:\/\/www.flipo-richir.eu\/wp-content\/uploads\/mise-en-service-du-6-eme-groupe-de-la-centrale-hydroelectrique-dedea-l-flipo-richir-3-80x80.jpg"},"grve-image-large-rect-horizontal":{"file":"mise-en-service-du-6-eme-groupe-de-la-centrale-hydroelectrique-dedea-l-flipo-richir-3-1170x658.jpg","width":1170,"height":658,"mime_type":"image\/jpeg","source_url":"https:\/\/www.flipo-richir.eu\/wp-content\/uploads\/mise-en-service-du-6-eme-groupe-de-la-centrale-hydroelectrique-dedea-l-flipo-richir-3-1170x658.jpg"},"grve-image-small-square":{"file":"mise-en-service-du-6-eme-groupe-de-la-centrale-hydroelectrique-dedea-l-flipo-richir-3-560x560.jpg","width":560,"height":560,"mime_type":"image\/jpeg","source_url":"https:\/\/www.flipo-richir.eu\/wp-content\/uploads\/mise-en-service-du-6-eme-groupe-de-la-centrale-hydroelectrique-dedea-l-flipo-richir-3-560x560.jpg"},"grve-image-small-rect-horizontal":{"file":"mise-en-service-du-6-eme-groupe-de-la-centrale-hydroelectrique-dedea-l-flipo-richir-3-560x315.jpg","width":560,"height":315,"mime_type":"image\/jpeg","source_url":"https:\/\/www.flipo-richir.eu\/wp-content\/uploads\/mise-en-service-du-6-eme-groupe-de-la-centrale-hydroelectrique-dedea-l-flipo-richir-3-560x315.jpg"},"grve-image-medium-rect-vertical":{"file":"mise-en-service-du-6-eme-groupe-de-la-centrale-hydroelectrique-dedea-l-flipo-richir-3-560x1120.jpg","width":560,"height":1120,"mime_type":"image\/jpeg","source_url":"https:\/\/www.flipo-richir.eu\/wp-content\/uploads\/mise-en-service-du-6-eme-groupe-de-la-centrale-hydroelectrique-dedea-l-flipo-richir-3-560x1120.jpg"},"grve-image-medium-rect-horizontal":{"file":"mise-en-service-du-6-eme-groupe-de-la-centrale-hydroelectrique-dedea-l-flipo-richir-3-1120x560.jpg","width":1120,"height":560,"mime_type":"image\/jpeg","source_url":"https:\/\/www.flipo-richir.eu\/wp-content\/uploads\/mise-en-service-du-6-eme-groupe-de-la-centrale-hydroelectrique-dedea-l-flipo-richir-3-1120x560.jpg"},"grve-image-medium-square":{"file":"mise-en-service-du-6-eme-groupe-de-la-centrale-hydroelectrique-dedea-l-flipo-richir-3-1120x1120.jpg","width":1120,"height":1120,"mime_type":"image\/jpeg","source_url":"https:\/\/www.flipo-richir.eu\/wp-content\/uploads\/mise-en-service-du-6-eme-groupe-de-la-centrale-hydroelectrique-dedea-l-flipo-richir-3-1120x1120.jpg"},"full":{"file":"mise-en-service-du-6-eme-groupe-de-la-centrale-hydroelectrique-dedea-l-flipo-richir-3.jpg","width":1200,"height":1600,"mime_type":"image\/jpeg","source_url":"https:\/\/www.flipo-richir.eu\/wp-content\/uploads\/mise-en-service-du-6-eme-groupe-de-la-centrale-hydroelectrique-dedea-l-flipo-richir-3.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/www.flipo-richir.eu\/wp-content\/uploads\/mise-en-service-du-6-eme-groupe-de-la-centrale-hydroelectrique-dedea-l-flipo-richir-3.jpg","filename":"mise-en-service-du-6-eme-groupe-de-la-centrale-hydroelectrique-dedea-l-flipo-richir-3.jpg","filesize":228514,"_links":{"self":[{"href":"https:\/\/www.flipo-richir.eu\/en\/wp-json\/wp\/v2\/media\/7502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.flipo-richir.eu\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.flipo-richir.eu\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.flipo-richir.eu\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.flipo-richir.eu\/en\/wp-json\/wp\/v2\/comments?post=7502"}]}}